{"id":2857,"count":3,"description":"","link":"https:\/\/heavensmetalmagazine.com\/index.php\/tag\/new-music\/","name":"New music","slug":"new-music","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New music Archives - Heaven&#039;s Metal Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/heavensmetalmagazine.com\/index.php\/tag\/new-music\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New music Archives - Heaven&#039;s Metal Magazine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/heavensmetalmagazine.com\/index.php\/tag\/new-music\/\" \/>\n<meta property=\"og:site_name\" content=\"Heaven&#039;s Metal Magazine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/index.php\\\/tag\\\/new-music\\\/\",\"url\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/index.php\\\/tag\\\/new-music\\\/\",\"name\":\"New music Archives - Heaven&#039;s Metal Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/index.php\\\/tag\\\/new-music\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/index.php\\\/tag\\\/new-music\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New music\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/#website\",\"url\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/\",\"name\":\"Heaven's Metal Magazine\",\"description\":\"The Official Website for Heaven&#039;s Metal Magazine [Est. 1985]\",\"publisher\":{\"@id\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/#organization\",\"name\":\"Heaven's Metal Magazine\",\"url\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Heavens-Metal-modern-logo.png\",\"contentUrl\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Heavens-Metal-modern-logo.png\",\"width\":1908,\"height\":456,\"caption\":\"Heaven's Metal Magazine\"},\"image\":{\"@id\":\"https:\\\/\\\/heavensmetalmagazine.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HeavensMetal\",\"https:\\\/\\\/www.instagram.com\\\/heavensmetal\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC60Tib86vnRv7obZ4rcQvSA\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/HM_(magazine)\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New music Archives - Heaven&#039;s Metal Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/heavensmetalmagazine.com\/index.php\/tag\/new-music\/","og_locale":"en_US","og_type":"article","og_title":"New music Archives - Heaven&#039;s Metal Magazine","og_url":"https:\/\/heavensmetalmagazine.com\/index.php\/tag\/new-music\/","og_site_name":"Heaven&#039;s Metal Magazine","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/heavensmetalmagazine.com\/index.php\/tag\/new-music\/","url":"https:\/\/heavensmetalmagazine.com\/index.php\/tag\/new-music\/","name":"New music Archives - Heaven&#039;s Metal Magazine","isPartOf":{"@id":"https:\/\/heavensmetalmagazine.com\/#website"},"breadcrumb":{"@id":"https:\/\/heavensmetalmagazine.com\/index.php\/tag\/new-music\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/heavensmetalmagazine.com\/index.php\/tag\/new-music\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/heavensmetalmagazine.com\/"},{"@type":"ListItem","position":2,"name":"New music"}]},{"@type":"WebSite","@id":"https:\/\/heavensmetalmagazine.com\/#website","url":"https:\/\/heavensmetalmagazine.com\/","name":"Heaven's Metal Magazine","description":"The Official Website for Heaven&#039;s Metal Magazine [Est. 1985]","publisher":{"@id":"https:\/\/heavensmetalmagazine.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/heavensmetalmagazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/heavensmetalmagazine.com\/#organization","name":"Heaven's Metal Magazine","url":"https:\/\/heavensmetalmagazine.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/heavensmetalmagazine.com\/#\/schema\/logo\/image\/","url":"https:\/\/heavensmetalmagazine.com\/wp-content\/uploads\/2020\/11\/Heavens-Metal-modern-logo.png","contentUrl":"https:\/\/heavensmetalmagazine.com\/wp-content\/uploads\/2020\/11\/Heavens-Metal-modern-logo.png","width":1908,"height":456,"caption":"Heaven's Metal Magazine"},"image":{"@id":"https:\/\/heavensmetalmagazine.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HeavensMetal","https:\/\/www.instagram.com\/heavensmetal\/","https:\/\/www.youtube.com\/channel\/UC60Tib86vnRv7obZ4rcQvSA","https:\/\/en.wikipedia.org\/wiki\/HM_(magazine)"]}]}},"_links":{"self":[{"href":"https:\/\/heavensmetalmagazine.com\/index.php\/wp-json\/wp\/v2\/tags\/2857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heavensmetalmagazine.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/heavensmetalmagazine.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/heavensmetalmagazine.com\/index.php\/wp-json\/wp\/v2\/posts?tags=2857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}